{"id":5969,"date":"2025-04-04T18:02:11","date_gmt":"2025-04-04T21:02:11","guid":{"rendered":"http:\/\/170.83.3.166:4180\/?p=5969"},"modified":"2025-04-04T18:02:11","modified_gmt":"2025-04-04T21:02:11","slug":"inscricoes-abertas-a-partir-do-dia-7-de-abril-para-a-campanha-de-castracao-gratuita-de-caes-e-gatos-no-municipio","status":"publish","type":"post","link":"http:\/\/170.83.3.166:4180\/index.php\/2025\/04\/04\/inscricoes-abertas-a-partir-do-dia-7-de-abril-para-a-campanha-de-castracao-gratuita-de-caes-e-gatos-no-municipio\/","title":{"rendered":"INSCRI\u00c7\u00d5ES ABERTAS A PARTIR DO DIA 7 DE ABRIL, PARA A CAMPANHA DE CASTRA\u00c7\u00c3O GRATUITA DE C\u00c3ES E GATOS NO MUNIC\u00cdPIO"},"content":{"rendered":"\n<p>As inscri\u00e7\u00f5es est\u00e3o abertas para toda a popula\u00e7\u00e3o, com PRIORIDADE para os inscritos no Cadastro \u00danico (Cad\u00danico), com apresenta\u00e7\u00e3o obrigat\u00f3ria do N\u00famero de Identifica\u00e7\u00e3o Social (NIS)<\/p>\n\n\n\n<p>As inscri\u00e7\u00f5es para a Campanha de Castra\u00e7\u00e3o Gratuita de C\u00e3es e Gatos 2025, que ser\u00e1 realizada nos dias 22,23 e 24 de abril no Munic\u00edpio estar\u00e3o abertas a partir da pr\u00f3xima segunda-feira, dia 7 de abril, das 8h \u00e0s 17h, exclusivamente pelo whatsapp da Vigil\u00e2ncia Sanit\u00e1ria (13) 3854-2214.<\/p>\n\n\n\n<p>O tutor do animal deve ser maior de idade, apresentar um documento original com foto e comprovante de resid\u00eancia do munic\u00edpio de Cajati.<\/p>\n\n\n\n<p>Castrar \u00e9 um ato de amor e responsabilidade!<\/p>\n\n\n\n<p>VAGAS LIMITADAS!<br>#castramovel #Cajati&nbsp;<br>#secretariadesaudedecajati<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As inscri\u00e7\u00f5es est\u00e3o abertas para toda a popula\u00e7\u00e3o, com PRIORIDADE para os inscritos no Cadastro \u00danico (Cad\u00danico), com apresenta\u00e7\u00e3o obrigat\u00f3ria do N\u00famero de Identifica\u00e7\u00e3o Social (NIS) As inscri\u00e7\u00f5es para a Campanha de Castra\u00e7\u00e3o Gratuita de C\u00e3es e Gatos 2025, que ser\u00e1 realizada nos dias 22,23 e 24 de abril no Munic\u00edpio estar\u00e3o abertas a partir [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5970,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5969","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"http:\/\/170.83.3.166:4180\/index.php\/wp-json\/wp\/v2\/posts\/5969","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/170.83.3.166:4180\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/170.83.3.166:4180\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/170.83.3.166:4180\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/170.83.3.166:4180\/index.php\/wp-json\/wp\/v2\/comments?post=5969"}],"version-history":[{"count":1,"href":"http:\/\/170.83.3.166:4180\/index.php\/wp-json\/wp\/v2\/posts\/5969\/revisions"}],"predecessor-version":[{"id":5971,"href":"http:\/\/170.83.3.166:4180\/index.php\/wp-json\/wp\/v2\/posts\/5969\/revisions\/5971"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/170.83.3.166:4180\/index.php\/wp-json\/wp\/v2\/media\/5970"}],"wp:attachment":[{"href":"http:\/\/170.83.3.166:4180\/index.php\/wp-json\/wp\/v2\/media?parent=5969"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/170.83.3.166:4180\/index.php\/wp-json\/wp\/v2\/categories?post=5969"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/170.83.3.166:4180\/index.php\/wp-json\/wp\/v2\/tags?post=5969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}